{"id":449,"date":"2025-08-18T03:35:17","date_gmt":"2025-08-18T03:35:17","guid":{"rendered":"https:\/\/www.emprendebox.es\/magia\/?page_id=449"},"modified":"2026-01-19T18:06:09","modified_gmt":"2026-01-19T18:06:09","slug":"empresas","status":"publish","type":"page","link":"https:\/\/www.emprendebox.es\/magia\/empresas\/","title":{"rendered":"Empresas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"449\" class=\"elementor elementor-449\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-493cb3dd elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"493cb3dd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62bd3fad\" data-id=\"62bd3fad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d4a8c1 elementor-widget elementor-widget-heading\" data-id=\"0d4a8c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Magia y Comunicaci\u00f3n para Empresas y Particulares<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a39ec5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a39ec5d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fc775fe\" data-id=\"6fc775fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-695b7b6 elementor-widget elementor-widget-heading\" data-id=\"695b7b6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si vas a organizar un evento\u2026 que nadie mire el m\u00f3vil.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b7741 elementor-widget elementor-widget-text-editor\" data-id=\"d4b7741\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Trabajo con empresas, instituciones y marcas que quieren salirse del PowerPoint y dejar huella.<\/span><\/p><p><span style=\"font-weight: 400;\">Combino la magia, la palabra y el pensamiento lateral para crear experiencias memorables.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00bfMi especialidad? Que tus ideas lleguen, se entiendan\u2026 y se recuerden.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-387b5cf6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"387b5cf6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-505a1a05\" data-id=\"505a1a05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1b5f9b elementor-widget elementor-widget-icon-box\" data-id=\"a1b5f9b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<br>C\u00d3CTEL\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(Magia discreta o apote\u00f3sica, t\u00fa eliges) \nCenas de empresa, recepciones, ferias, convenciones\u2026 Me muevo entre grupos reducidos, creo momentos \u00fanicos y saco sonrisas con un estilo elegante y cuidado.\n\u00bfQuieres algo m\u00e1s llamativo? Tambi\u00e9n puedo hacer un show para todos los asistentes.\nAct\u00fao en eventos privados donde la discreci\u00f3n es clave\u2026 y la sorpresa, tambi\u00e9n.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-16eb547\" data-id=\"16eb547\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e74de elementor-widget elementor-widget-image\" data-id=\"b4e74de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg\" class=\"attachment-large size-large wp-image-842\" alt=\"\" srcset=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg 800w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1-300x225.jpg 300w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11bce0d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11bce0d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32450e73\" data-id=\"32450e73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae4a97 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6ae4a97\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0071x-1.jpg\" class=\"attachment-large size-large wp-image-844\" alt=\"\" srcset=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0071x-1.jpg 800w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0071x-1-300x225.jpg 300w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0071x-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66b5143a\" data-id=\"66b5143a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45945344 elementor-widget elementor-widget-icon-box\" data-id=\"45945344\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<br><br>FORMACIONES\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(De la varita al aula o al escenario)\nImparto talleres y conferencias donde la magia se convierte en una herramienta pedag\u00f3gica o comunicativa.\nDesde clases particulares de magia (para todos los niveles), hasta sesiones espec\u00edficas como:\n\nLa magia como recurso did\u00e1ctico en las matem\u00e1ticas\n\nIngeniero de ilusiones (conferencia inspiracional para empresas)\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a3349e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a3349e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f622ba\" data-id=\"1f622ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43acee17 elementor-widget elementor-widget-icon-box\" data-id=\"43acee17\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<br><br>ASESOR\u00cdA\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(S\u00ed, tambi\u00e9n doy ideas)\nTrabajo con artistas, directivos y equipos creativos para aplicar principios m\u00e1gicos a sus proyectos.\nPensamiento lateral, t\u00e9cnicas de atenci\u00f3n y narrativas sorprendentes.\nPresencial u online. Para una sesi\u00f3n puntual o para acompa\u00f1arte en el proceso.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c8f901b\" data-id=\"c8f901b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e36b2f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0e36b2f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/2-2.jpg\" class=\"attachment-large size-large wp-image-845\" alt=\"\" srcset=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/2-2.jpg 800w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/2-2-300x225.jpg 300w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/2-2-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8512671 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8512671\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0de33ae\" data-id=\"0de33ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e4506 elementor-widget elementor-widget-image\" data-id=\"71e4506\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0453x-1.jpg\" class=\"attachment-large size-large wp-image-846\" alt=\"\" srcset=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0453x-1.jpg 800w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0453x-1-300x225.jpg 300w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/Diego-0453x-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c7d669\" data-id=\"6c7d669\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-728ebd56 elementor-widget elementor-widget-icon-box\" data-id=\"728ebd56\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<br><br>TEAM BUILDING\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(O c\u00f3mo unir equipos sin hacer gincanas)\nDise\u00f1o sesiones participativas donde el objetivo no es correr por una oficina, sino aprender mientras se juega.\nTrabajo con los valores y necesidades de tu empresa para crear din\u00e1micas m\u00e1gicas, entretenidas y efectivas.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fcb8dbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcb8dbe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-001c5d8\" data-id=\"001c5d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-565f70b8 elementor-widget elementor-widget-icon-box\" data-id=\"565f70b8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<br><br>IMAGEN DE MARCA\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(Branding con efectos especiales)\n\u00bfY si en lugar de contar tu idea\u2026 la hicieras aparecer entre aplausos?\nUso la magia como herramienta para que el mensaje de tu empresa impacte, emocione y se quede en la memoria.\nReuniones, presentaciones de producto o acciones de marca con un efecto wow real.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d872674\" data-id=\"d872674\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f63630 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7f63630\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/BodaLaura_Nicko.08.08.2020-862-1.jpg\" class=\"attachment-large size-large wp-image-847\" alt=\"\" srcset=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/BodaLaura_Nicko.08.08.2020-862-1.jpg 800w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/BodaLaura_Nicko.08.08.2020-862-1-300x225.jpg 300w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/BodaLaura_Nicko.08.08.2020-862-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-37394bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37394bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1afd7fe\" data-id=\"1afd7fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4259e20 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4259e20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/DSC0096-1-1.jpg\" class=\"attachment-large size-large wp-image-848\" alt=\"\" srcset=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/DSC0096-1-1.jpg 800w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/DSC0096-1-1-300x225.jpg 300w, https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/DSC0096-1-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37861eb\" data-id=\"37861eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75779565 elementor-widget elementor-widget-icon-box\" data-id=\"75779565\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<br><br>PRESENTADOR\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(Maestro de ceremonias con un as bajo la manga)\nGalas, entregas de premios, presentaciones corporativas\u2026 Si buscas a alguien que lleve el ritmo del evento con carisma, humor y un punto de magia: ese soy yo.\nConvierto el t\u00edpico \u201csiguiente ponente\u201d en un momento de atenci\u00f3n total.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4707e1a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4707e1a5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c99bb7b\" data-id=\"3c99bb7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54bf8009 elementor-widget elementor-widget-heading\" data-id=\"54bf8009\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCon qui\u00e9n he trabajado? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90e28f9 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"90e28f9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;5&quot;,&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/2-300x124.png\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/4-300x150.png\" alt=\"4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/5-300x79.png\" alt=\"5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/6.1-300x120.webp\" alt=\"6.1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/6-300x122.png\" alt=\"6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/7.png\" alt=\"7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/8.1-1-300x106.png\" alt=\"8.1 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/8.png\" alt=\"8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/9.0.png\" alt=\"9.0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/9.1-300x78.png\" alt=\"9.1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/9.2-300x300.png\" alt=\"9.2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/11.1-300x146.png\" alt=\"11.1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/11.2-300x200.jpg\" alt=\"11.2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/13.3-300x300.png\" alt=\"13.3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/13.4-300x169.png\" alt=\"13.4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/14-300x75.jpeg\" alt=\"14\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/16-300x169.png\" alt=\"16\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/17-300x90.png\" alt=\"17\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/18.png\" alt=\"18\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/19.png\" alt=\"19\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/20-300x300.png\" alt=\"20\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/21.png\" alt=\"21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/22-300x113.png\" alt=\"22\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/22-la-fidula.png\" alt=\"22-la-fidula\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/23.png\" alt=\"23\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/25-300x102.png\" alt=\"25\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/26.png\" alt=\"26\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/27-300x152.jpg\" alt=\"27\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/28-300x176.png\" alt=\"28\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/29.png\" alt=\"29\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/30.png\" alt=\"30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/31-300x150.png\" alt=\"31\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/32.png\" alt=\"32\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/33-300x300.png\" alt=\"33\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/34-300x157.png\" alt=\"34\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/35.png\" alt=\"35\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/36-300x90.png\" alt=\"36\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/38.png\" alt=\"38\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/39-300x152.png\" alt=\"39\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"40 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/40-300x300.png\" alt=\"40\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"41 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/41.png\" alt=\"41\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"42 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/42.png\" alt=\"42\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"43 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/43-300x225.png\" alt=\"43\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"44 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/44.png\" alt=\"44\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"45 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/45-300x152.png\" alt=\"45\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"46 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/46-300x137.png\" alt=\"46\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"47 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/47.png\" alt=\"47\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"48 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/48.png\" alt=\"48\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"49 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/49.png\" alt=\"49\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"50 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/50.png\" alt=\"50\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"51 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/51.png\" alt=\"51\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"52 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/1-300x72.jpeg\" alt=\"1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"53 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/3-1-300x169.png\" alt=\"3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"54 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/11.0-1.png\" alt=\"11.0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"55 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/13.2-1.png\" alt=\"13.2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"56 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/13.5-1.png\" alt=\"13.5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"57 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/15.png\" alt=\"15\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"58 de 58\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/37-1.png\" alt=\"37\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-195f7e84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"195f7e84\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d6c3a5b\" data-id=\"2d6c3a5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-73aae594 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73aae594\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1497b7cf\" data-id=\"1497b7cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7330b96d elementor-widget elementor-widget-heading\" data-id=\"7330b96d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eventos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14c436d elementor-widget elementor-widget-gallery\" data-id=\"14c436d\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:3,&quot;aspect_ratio&quot;:&quot;1:1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/Imagen-de-WhatsApp-2025-07-10-a-las-16.23.49_c18cb0ae.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c436d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzcwLCJ1cmwiOiJodHRwczpcL1wvd3d3LmVtcHJlbmRlYm94LmVzXC9tYWdpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL0ltYWdlbi1kZS1XaGF0c0FwcC0yMDI1LTA3LTEwLWEtbGFzLTE2LjIzLjQ5X2MxOGNiMGFlLmpwZyIsInNsaWRlc2hvdyI6IjE0YzQzNmQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/Imagen-de-WhatsApp-2025-07-10-a-las-16.23.49_c18cb0ae-768x956.jpg\" data-width=\"768\" data-height=\"956\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/1702982396075.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c436d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzY5LCJ1cmwiOiJodHRwczpcL1wvd3d3LmVtcHJlbmRlYm94LmVzXC9tYWdpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcLzE3MDI5ODIzOTYwNzUuanBnIiwic2xpZGVzaG93IjoiMTRjNDM2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/1702982396075-768x359.jpg\" data-width=\"768\" data-height=\"359\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/portada.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c436d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc0LCJ1cmwiOiJodHRwczpcL1wvd3d3LmVtcHJlbmRlYm94LmVzXC9tYWdpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL3BvcnRhZGEuanBnIiwic2xpZGVzaG93IjoiMTRjNDM2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/portada-768x502.jpg\" data-width=\"768\" data-height=\"502\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/IMG-20210918-WA0002.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c436d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzcyLCJ1cmwiOiJodHRwczpcL1wvd3d3LmVtcHJlbmRlYm94LmVzXC9tYWdpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL0lNRy0yMDIxMDkxOC1XQTAwMDIuanBnIiwic2xpZGVzaG93IjoiMTRjNDM2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/IMG-20210918-WA0002-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/IMG_20210918_174703.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c436d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzcxLCJ1cmwiOiJodHRwczpcL1wvd3d3LmVtcHJlbmRlYm94LmVzXC9tYWdpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL0lNR18yMDIxMDkxOF8xNzQ3MDMuanBnIiwic2xpZGVzaG93IjoiMTRjNDM2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/IMG_20210918_174703.jpg\" data-width=\"756\" data-height=\"1006\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/IMG-20210918-WA0015.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c436d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzczLCJ1cmwiOiJodHRwczpcL1wvd3d3LmVtcHJlbmRlYm94LmVzXC9tYWdpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL0lNRy0yMDIxMDkxOC1XQTAwMTUuanBnIiwic2xpZGVzaG93IjoiMTRjNDM2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/11\/IMG-20210918-WA0015.jpg\" data-width=\"768\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0320d1d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0320d1d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-471e00a\" data-id=\"471e00a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5688f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5688f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f78ad6a\" data-id=\"f78ad6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a57d576 elementor-widget elementor-widget-heading\" data-id=\"a57d576\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lo que cuentan de mi:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6249a86 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"6249a86\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;speed&quot;:1000,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201cLas manos de Diego fluyen con la naturalidad y el virtuosismo de los grandes. Su discurso consigue crear una atm\u00f3sfera extraordinaria. \u00a1Lo que vives es magia aut\u00e9ntica!\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/2.-Miquel-Ortega-Director-de-Orquesta-y-Compositor.jpg\" alt=\"Miquel Ortega\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Miquel Ortega<\/span><span class=\"elementor-testimonial__title\">Director de Orquesta, Compositor y Pianista<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201cDiego tiene alma po\u00e9tica. Realiza una magia que es manifestaci\u00f3n de un sentimiento. Posee el don de la verdad, le admiro. He disfrutado much\u00edsimo, Diego es Imprescindible.\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/1.-Ramon-Mayrata-Escritor.-Antropologo-e-Historiador.jpg\" alt=\"Ram\u00f3n Mayrata\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Ram\u00f3n Mayrata<\/span><span class=\"elementor-testimonial__title\">Escritor, Antrop\u00f3logo e Historiador<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e9c6130 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e9c6130\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f45ec6a\" data-id=\"f45ec6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21de2ea0 elementor-widget elementor-widget-heading\" data-id=\"21de2ea0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfHablamos de magia? \u00bfQuieres que pase algo especial en tu pr\u00f3ximo evento?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7039c7d elementor-widget elementor-widget-text-editor\" data-id=\"7039c7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">D\u00e9jame tus datos y te escribir\u00e9 personalmente para enviarte ideas, disponibilidad y una propuesta que se adapte a lo que necesitas.<\/span><\/p><p><span style=\"font-weight: 400;\">Sin humo. Solo magia real.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41809e12 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"41809e12\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+34627221679%20\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+34 627 221 679 <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:hola@mellamodiego.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">hola@mellamodiego.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21f18692 elementor-widget elementor-widget-spacer\" data-id=\"21f18692\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7185d97a\" data-id=\"7185d97a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96718af elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"96718af\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formulario Diego Mu\u00f1oz\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"449\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"96718af\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Empresas - Diego Mu\u00f1oz\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"449\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNombre\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Nombre*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_3b7c8dc elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3b7c8dc\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_3b7c8dc]\" id=\"form-field-field_3b7c8dc\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Tel\u00e9fono*\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Correo Electr\u00f3nico*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMensaje\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensaje*\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_533220b elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_533220b\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcJf6orAAAAAPpRTBtCGxzxVSDxfNWXT3uffk57\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Magia y Comunicaci\u00f3n para Empresas y Particulares Si vas a organizar un evento\u2026 que nadie mire el m\u00f3vil. Trabajo con empresas, instituciones y marcas que quieren salirse del PowerPoint y dejar huella. Combino la magia, la palabra y el pensamiento lateral para crear experiencias memorables. \u00bfMi especialidad? Que tus ideas lleguen, se entiendan\u2026 y se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-449","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Empresas - Diego Mu\u00f1oz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emprendebox.es\/magia\/empresas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresas - Diego Mu\u00f1oz\" \/>\n<meta property=\"og:description\" content=\"Magia y Comunicaci\u00f3n para Empresas y Particulares Si vas a organizar un evento\u2026 que nadie mire el m\u00f3vil. Trabajo con empresas, instituciones y marcas que quieren salirse del PowerPoint y dejar huella. Combino la magia, la palabra y el pensamiento lateral para crear experiencias memorables. \u00bfMi especialidad? Que tus ideas lleguen, se entiendan\u2026 y se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emprendebox.es\/magia\/empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"Diego Mu\u00f1oz\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T18:06:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/\",\"url\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/\",\"name\":\"Empresas - Diego Mu\u00f1oz\",\"isPartOf\":{\"@id\":\"https:\/\/www.emprendebox.es\/magia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg\",\"datePublished\":\"2025-08-18T03:35:17+00:00\",\"dateModified\":\"2026-01-19T18:06:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emprendebox.es\/magia\/empresas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/#primaryimage\",\"url\":\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg\",\"contentUrl\":\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emprendebox.es\/magia\/empresas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.emprendebox.es\/magia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emprendebox.es\/magia\/#website\",\"url\":\"https:\/\/www.emprendebox.es\/magia\/\",\"name\":\"Diego Mu\u00f1oz\",\"description\":\"Mago\",\"publisher\":{\"@id\":\"https:\/\/www.emprendebox.es\/magia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emprendebox.es\/magia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emprendebox.es\/magia\/#organization\",\"name\":\"Diego Mu\u00f1oz\",\"url\":\"https:\/\/www.emprendebox.es\/magia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.emprendebox.es\/magia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/logo-1-home.jpg\",\"contentUrl\":\"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/logo-1-home.jpg\",\"width\":1581,\"height\":1097,\"caption\":\"Diego Mu\u00f1oz\"},\"image\":{\"@id\":\"https:\/\/www.emprendebox.es\/magia\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresas - Diego Mu\u00f1oz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emprendebox.es\/magia\/empresas\/","og_locale":"es_ES","og_type":"article","og_title":"Empresas - Diego Mu\u00f1oz","og_description":"Magia y Comunicaci\u00f3n para Empresas y Particulares Si vas a organizar un evento\u2026 que nadie mire el m\u00f3vil. Trabajo con empresas, instituciones y marcas que quieren salirse del PowerPoint y dejar huella. Combino la magia, la palabra y el pensamiento lateral para crear experiencias memorables. \u00bfMi especialidad? Que tus ideas lleguen, se entiendan\u2026 y se [&hellip;]","og_url":"https:\/\/www.emprendebox.es\/magia\/empresas\/","og_site_name":"Diego Mu\u00f1oz","article_modified_time":"2026-01-19T18:06:09+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emprendebox.es\/magia\/empresas\/","url":"https:\/\/www.emprendebox.es\/magia\/empresas\/","name":"Empresas - Diego Mu\u00f1oz","isPartOf":{"@id":"https:\/\/www.emprendebox.es\/magia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emprendebox.es\/magia\/empresas\/#primaryimage"},"image":{"@id":"https:\/\/www.emprendebox.es\/magia\/empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg","datePublished":"2025-08-18T03:35:17+00:00","dateModified":"2026-01-19T18:06:09+00:00","breadcrumb":{"@id":"https:\/\/www.emprendebox.es\/magia\/empresas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emprendebox.es\/magia\/empresas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emprendebox.es\/magia\/empresas\/#primaryimage","url":"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg","contentUrl":"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2026\/01\/1702982396091-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.emprendebox.es\/magia\/empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.emprendebox.es\/magia\/"},{"@type":"ListItem","position":2,"name":"Empresas"}]},{"@type":"WebSite","@id":"https:\/\/www.emprendebox.es\/magia\/#website","url":"https:\/\/www.emprendebox.es\/magia\/","name":"Diego Mu\u00f1oz","description":"Mago","publisher":{"@id":"https:\/\/www.emprendebox.es\/magia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emprendebox.es\/magia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emprendebox.es\/magia\/#organization","name":"Diego Mu\u00f1oz","url":"https:\/\/www.emprendebox.es\/magia\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emprendebox.es\/magia\/#\/schema\/logo\/image\/","url":"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/logo-1-home.jpg","contentUrl":"https:\/\/www.emprendebox.es\/magia\/wp-content\/uploads\/2025\/08\/logo-1-home.jpg","width":1581,"height":1097,"caption":"Diego Mu\u00f1oz"},"image":{"@id":"https:\/\/www.emprendebox.es\/magia\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/pages\/449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/comments?post=449"}],"version-history":[{"count":73,"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/pages\/449\/revisions"}],"predecessor-version":[{"id":882,"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/pages\/449\/revisions\/882"}],"wp:attachment":[{"href":"https:\/\/www.emprendebox.es\/magia\/wp-json\/wp\/v2\/media?parent=449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}